{"id":1230,"date":"2018-01-09T16:06:57","date_gmt":"2018-01-09T15:06:57","guid":{"rendered":"http:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg"},"modified":"2018-01-09T16:06:57","modified_gmt":"2018-01-09T15:06:57","slug":"leo-mosto-parzialmente-fermentato-di-moscato-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.aziendaguerrieri.it\/en\/prodotto\/leo-mosto-parzialmente-fermentato-di-moscato\/leo-mosto-parzialmente-fermentato-di-moscato-2-2\/","title":{"rendered":"LEO \u2013 Mosto parzialmente fermentato di Moscato"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-1230","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-300x300.jpg 300w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-150x150.jpg 150w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-768x768.jpg 768w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1024x1024.jpg 1024w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-146x146.jpg 146w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-50x50.jpg 50w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-75x75.jpg 75w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-85x85.jpg 85w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-80x80.jpg 80w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-720x720.jpg 720w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-675x675.jpg 675w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg 1200w\" sizes=\"auto, (max-width:767px) 300px, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1200,"height":1200,"file":"2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg","sizes":{"thumbnail":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-150x150.jpg"},"medium":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-300x300.jpg"},"medium_large":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-768x768.jpg"},"large":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1024x1024.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1024x1024.jpg"},"post-thumbnail":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-146x146.jpg","width":146,"height":146,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-146x146.jpg"},"50x50":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-50x50.jpg","width":50,"height":50,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-50x50.jpg"},"clients-slider":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-75x75.jpg","width":75,"height":75,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-75x75.jpg"},"slider-content":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x860.jpg","width":1200,"height":860,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x860.jpg"},"testimonials":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-85x85.jpg","width":85,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-85x85.jpg"},"blog-navi":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-80x80.jpg"},"portfolio-mf":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x1000.jpg","width":1200,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x1000.jpg"},"portfolio-mf-w":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x500.jpg","width":1200,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x500.jpg"},"portfolio-mf-t":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-768x1200.jpg","width":768,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-768x1200.jpg"},"portfolio-list":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x750.jpg","width":1200,"height":750,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-1200x750.jpg"},"blog-portfolio":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-720x720.jpg","width":720,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-720x720.jpg"},"blog-single":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-675x675.jpg","width":675,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato-675x675.jpg"},"full":{"file":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"Copyright: Guerrieriadv","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1229,"source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/01\/LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg","filename":"LEO-\u2013-Mosto-parzialmente-fermentato-di-Moscato.jpg","filesize":88715,"_links":{"self":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media\/1230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/comments?post=1230"}],"wp:attached-to":[{"embeddable":true,"post_type":"portfolio","id":1229,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/portfolio\/1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}