{"id":1569,"date":"2017-10-30T15:59:01","date_gmt":"2017-10-30T14:59:01","guid":{"rendered":"http:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg"},"modified":"2017-10-30T15:59:01","modified_gmt":"2017-10-30T14:59:01","slug":"guerrieri-mockup-sito-websettembre","status":"inherit","type":"attachment","link":"https:\/\/www.aziendaguerrieri.it\/en\/guerrieri-mockup-sito-websettembre\/","title":{"rendered":"Guerrieri&#8212;Mockup-sito-webSETTEMBRE"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-1569","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"144\" src=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-300x144.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-300x144.jpg 300w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-768x369.jpg 768w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1024x492.jpg 1024w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-260x125.jpg 260w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-50x24.jpg 50w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-150x72.jpg 150w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-960x461.jpg 960w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1200x576.jpg 1200w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg 1400w\" sizes=\"auto, (max-width:767px) 300px, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1400,"height":672,"file":"2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg","sizes":{"thumbnail":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-150x150.jpg"},"medium":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-300x144.jpg","width":300,"height":144,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-300x144.jpg"},"medium_large":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-768x369.jpg","width":768,"height":369,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-768x369.jpg"},"large":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-1024x492.jpg","width":1024,"height":492,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1024x492.jpg"},"post-thumbnail":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-260x125.jpg","width":260,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-260x125.jpg"},"50x50":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-50x24.jpg","width":50,"height":24,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-50x24.jpg"},"clients-slider":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-150x72.jpg","width":150,"height":72,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-150x72.jpg"},"testimonials":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-85x85.jpg","width":85,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-85x85.jpg"},"blog-navi":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-80x80.jpg"},"portfolio-mf":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-1280x672.jpg","width":1280,"height":672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1280x672.jpg"},"portfolio-mf-w":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-1280x500.jpg","width":1280,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1280x500.jpg"},"portfolio-mf-t":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-768x672.jpg","width":768,"height":672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-768x672.jpg"},"blog-portfolio":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-960x461.jpg","width":960,"height":461,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-960x461.jpg"},"blog-single":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE-1200x576.jpg","width":1200,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE-1200x576.jpg"},"full":{"file":"Guerrieri-Mockup-sito-webSETTEMBRE.jpg","width":1400,"height":672,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2017\/10\/Guerrieri-Mockup-sito-webSETTEMBRE.jpg","filename":"Guerrieri-Mockup-sito-webSETTEMBRE.jpg","filesize":93673,"_links":{"self":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media\/1569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/comments?post=1569"}]}}