{"id":1682,"date":"2018-04-11T15:43:37","date_gmt":"2018-04-11T13:43:37","guid":{"rendered":"http:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale.jpg"},"modified":"2018-04-11T15:43:37","modified_gmt":"2018-04-11T13:43:37","slug":"header_tour_aziendale","status":"inherit","type":"attachment","link":"https:\/\/www.aziendaguerrieri.it\/en\/header_tour_aziendale\/","title":{"rendered":"header_tour_aziendale"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-1682","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"98\" src=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-300x98.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-300x98.jpg 300w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-768x251.jpg 768w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1024x335.jpg 1024w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-260x85.jpg 260w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-50x16.jpg 50w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-150x49.jpg 150w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale.jpg 1920w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-960x314.jpg 960w, https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1200x393.jpg 1200w\" sizes=\"auto, (max-width:767px) 300px, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":628,"file":"2018\/04\/header_tour_aziendale.jpg","sizes":{"thumbnail":{"file":"header_tour_aziendale-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-150x150.jpg"},"medium":{"file":"header_tour_aziendale-300x98.jpg","width":300,"height":98,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-300x98.jpg"},"medium_large":{"file":"header_tour_aziendale-768x251.jpg","width":768,"height":251,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-768x251.jpg"},"large":{"file":"header_tour_aziendale-1024x335.jpg","width":1024,"height":335,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1024x335.jpg"},"post-thumbnail":{"file":"header_tour_aziendale-260x85.jpg","width":260,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-260x85.jpg"},"50x50":{"file":"header_tour_aziendale-50x16.jpg","width":50,"height":16,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-50x16.jpg"},"clients-slider":{"file":"header_tour_aziendale-150x49.jpg","width":150,"height":49,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-150x49.jpg"},"slider-content":{"file":"header_tour_aziendale-1630x628.jpg","width":1630,"height":628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1630x628.jpg"},"testimonials":{"file":"header_tour_aziendale-85x85.jpg","width":85,"height":85,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-85x85.jpg"},"blog-navi":{"file":"header_tour_aziendale-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-80x80.jpg"},"portfolio-mf":{"file":"header_tour_aziendale-1280x628.jpg","width":1280,"height":628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1280x628.jpg"},"portfolio-mf-w":{"file":"header_tour_aziendale-1280x500.jpg","width":1280,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1280x500.jpg"},"portfolio-mf-t":{"file":"header_tour_aziendale-768x628.jpg","width":768,"height":628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-768x628.jpg"},"portfolio-list":{"file":"header_tour_aziendale-1920x628.jpg","width":1920,"height":628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1920x628.jpg"},"blog-portfolio":{"file":"header_tour_aziendale-960x314.jpg","width":960,"height":314,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-960x314.jpg"},"blog-single":{"file":"header_tour_aziendale-1200x393.jpg","width":1200,"height":393,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale-1200x393.jpg"},"full":{"file":"header_tour_aziendale.jpg","width":1920,"height":628,"mime_type":"image\/jpeg","source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.aziendaguerrieri.it\/wp-content\/uploads\/2018\/04\/header_tour_aziendale.jpg","filename":"header_tour_aziendale.jpg","filesize":491135,"_links":{"self":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media\/1682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aziendaguerrieri.it\/en\/wp-json\/wp\/v2\/comments?post=1682"}]}}